{"id":460,"date":"2020-06-24T18:06:49","date_gmt":"2020-06-24T16:06:49","guid":{"rendered":"https:\/\/www.antrag24.de\/c\/?p=460"},"modified":"2020-06-24T18:18:34","modified_gmt":"2020-06-24T16:18:34","slug":"geburtsurkunde-verloren","status":"publish","type":"post","link":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/","title":{"rendered":"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen"},"content":{"rendered":"<p>Die Geburtsurkunde geh\u00f6rt mit zu den wichtigsten Dokumenten, die Sie f\u00fcr unterschiedliche Anl\u00e4sse ben\u00f6tigen. Dazu geh\u00f6rt zum Beispiel der Antrag auf Mitgliedschaft bei der Krankenkasse, die Anmeldung Ihrer Hochzeit auf dem Standesamt, oder aber die Er\u00f6ffnung eines neuen Bankkontos. Wie das Leben aber leider manchmal spielt, <strong>gehen Dokumente gerne verloren<\/strong>. Nun stellt sich die Frage, ob es schwierig ist, eine verlorene <strong>Geburtsurkunde neu beantragen<\/strong> zu lassen und wie hoch die Kosten bei Verlust der Geburtsurkunde sind. Geht das \u00fcberhaupt so einfach und warum kann man nicht einfach auf eine Kopie zur\u00fcckgreifen? Wir behandeln nachfolgend die besagten Themen und erl\u00e4utern ebenfalls, wie man es am besten angeht, wenn man seine ausl\u00e4ndische Geburtsurkunde verloren hat.<\/p>\n<p><!--more--><\/p>\n<div class=\"schema-faq wp-block-yoast-faq-block\"><br \/>\n<div class=\"schema-faq-section\"><div itemscope=\"\" itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div itemprop=\"name\"><strong class=\"schema-faq-question\">Was ist der Unterschied zwischen Geburtsurkunde, der beglaubigten Abschrift aus dem Geburtenregister und der Abstammungsurkunde?<\/strong><\/div><div itemscope=\"\" itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\"><div itemprop=\"text\"><p class=\"schema-faq-answer\">Bei der Geburtsurkunde handelt es sich um ein Dokument, welches s\u00e4mtliche Informationen zu einer Person erh\u00e4lt. Dazu geh\u00f6rt der vollst\u00e4ndige Name, das Geschlecht, sowie die Namen seiner Eltern. Die Abstammungsurkunde, die seit dem 1. Januar 2009 mit jeder Geburtsurkunde ausgeh\u00e4ndigt wird, enth\u00e4lt zudem Informationen \u00fcber die leiblichen Eltern, sofern diese sich von den sorgeberechtigten unterscheiden. Die beglaubigte Abschrift hingegen ist eine Kopie aus dem Geburtenregister. In ihr sind auch s\u00e4mtliche Ver\u00e4nderungen vermerkt. Letzteres ben\u00f6tigen Sie f\u00fcr Beh\u00f6rdeng\u00e4nge und weiteres.<\/p><\/div><\/div><\/div><\/div><br \/>\n<div class=\"schema-faq-section\"><div itemscope=\"\" itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div itemprop=\"name\"><strong class=\"schema-faq-question\">Ist die Neuausstellung der Geburtsurkunde mit Problemen verbunden?<\/strong><\/div><div itemscope=\"\" itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\"><div itemprop=\"text\"><p class=\"schema-faq-answer\">Nein, eine Geburtsurkunde kann jederzeit neu ausgestellt werden. Allerdings ist die Neuausstellung unter Umst\u00e4nden mit gewissen Geb\u00fchren und Wartezeiten verbunden.<\/p><\/div><\/div><\/div><\/div><br \/>\n<div class=\"schema-faq-section\"><div itemscope=\"\" itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div itemprop=\"name\"><strong class=\"schema-faq-question\">Was tun, wenn Sie die Geburtsurkunde im Ausland verloren haben?<\/strong><\/div><div itemscope=\"\" itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\"><div itemprop=\"text\"><p class=\"schema-faq-answer\">Wenn Sie Ihre Geburtsurkunde verloren haben und im Ausland geboren wurden, k\u00f6nnen Sie unter gewissen Voraussetzungen eine Neuausstellung auch von Deutschland aus beantragen. M\u00f6glich wird dies ganz einfach durch einen Online-Antrag.<\/p><\/div><\/div><\/div><\/div><br \/>\n<\/div>\n<h2>Geburtsurkunde verloren &#8211; Wo bekomme ich eine Neue her?<\/h2>\n<figure id=\"attachment_482\" aria-describedby=\"caption-attachment-482\" style=\"width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-482 size-medium\" src=\"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-300x200.jpeg\" alt=\"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-300x200.jpeg 300w, https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-1024x684.jpeg 1024w, https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-768x513.jpeg 768w, https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-1536x1026.jpeg 1536w, https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-2048x1368.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-482\" class=\"wp-caption-text\">Wenn Sie eine Geburtsurkunde verloren haben, kann diese problemlos beim Standesamt neu beantragt werden.<\/figcaption><\/figure>\n<p>Wenn die <a href=\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-kosten\/\">Geburtsurkunde<\/a> des Kindes verloren gegangen ist und man eine neue anfordern m\u00f6chte, ist hierf\u00fcr das Standesamt zust\u00e4ndig. Dabei handelt es sich grunds\u00e4tzlich um das<strong> Standesamt des Geburtsortes<\/strong>. Da in der heutigen Zeit jedoch viele Menschen in eine v\u00f6llig andere Stadt umziehen, gestaltet sich dies in manchen F\u00e4llen scheinbar schwierig. Das gilt auch f\u00fcr jene, die ihre Geburtsurkunde im Ausland verloren haben.<\/p>\n<p>In diesem Fall ist es gut zu wissen, dass man die Geburtsurkunde auch jederzeit online anfordern kann.<\/p>\n<ul>\n<li>Hier w\u00e4hlt man das entsprechend zust\u00e4ndige Standesamt aus,<\/li>\n<li>gibt weitere Angaben in das Online-Formular ein<\/li>\n<li>und sendet den Antrag ab.<\/li>\n<\/ul>\n<p>Wenn man das Geburtsurkunde Original verloren hat, ist dies eine gute Alternative.<\/p>\n<div class=\"clk-widget clickout\"><a href=\"https:\/\/www.antrag24.de\/\" target=\"_blank\"><span class=\"top\">Geburtsurkunden schnell &amp; unkompliziert beantragen?<\/span><span class=\"bottom\">Um Ihre gew\u00fcnschten Urkunden beim Standesamt zu beantragen, gehen Sie wie folgt vor:<ul><li>Online Formular in weniger als 3 Minuten ausf\u00fcllen<\/li><li>Durch den Online-Prozess wird Ihr Antrag beim Standesamt unverz\u00fcglich bearbeitet<\/li><li>Sie erhalten Ihre gew\u00fcnschten Urkunden blitzschnell per Post<\/li><\/ul><span class=\"button\">\u00bb Jetzt Geburtsurkunden beantragen<\/span><div class=\"clear\"><\/div><\/span><\/a><\/div><p><\/p>\n<h2>Was muss ich tun und beachten?<\/h2>\n<p>Wenn Sie Ihre deutsche Geburtsurkunde verloren haben, ist es unerheblich, ob Sie sich gerade in Berlin, Hamburg, K\u00f6ln, Bremen oder Wuppertal befinden. Wenn Ihr zust\u00e4ndiges Standesamt in M\u00fcnchen oder Frankfurt liegt, k\u00f6nnen Sie dies ganz einfach <strong>mittels Online-Formular erledigen<\/strong>. Eine verlorene Geburtsurkunde neu beantragen kostet nur wenige Minuten und w\u00e4re sogar m\u00f6glich, wenn Sie sich gerade in \u00d6sterreich befinden.<\/p>\n<p>Weitere Unterlagen sind f\u00fcr die Anforderung einer Neuausstellung nicht erforderlich, denn Eltern sind stets dazu verpflichtet, ein <strong>Neugeborenes binnen einer Woche nach der Geburt dem Standesamt zu melden<\/strong>, damit es im Geburtenregister eingetragen wird. Somit wird auch die allererste Geburtsurkunde ausgestellt. Nachdrucke lassen sich somit ohne Problem herstellen.<\/p>\n<div class=\"tipp\">\n<div class=\"tipp-titel\">Wichtig: Wartezeit beachten und Vollmacht ausstellen<\/div>\n<div class=\"tipp-inhalt\">Beachten Sie, dass es zu gewissen Wartezeiten kommt, wenn Sie die Geburtsurkunde vom Kind nachfordern. Sofern Sie die Geburtsurkunde vom Sohn verloren oder von der Tochter verloren haben, k\u00f6nnen Sie diese als Eltern jederzeit nachfordern. Verwandte, die aus der direkten Linie stammen, werden hierbei ebenfalls keine Schwierigkeiten haben. Andere Personen hingegen m\u00fcssen es glaubhaft machen, wenn sie eine Geburtsurkunde vom Baby beantragen und sie nicht mit ihm verwandt sind. F\u00fcr den Fall sollten Sie eine Vollmacht ausstellen.<\/div>\n<\/div>\n<p><strong>Wenn Sie ein Ausl\u00e4nder oder Sp\u00e4taussiedler sind, haben Sie folgende Optionen:<\/strong><\/p>\n<ul>\n<li>Erkundigen Sie sich beim Standesamt, ob die Ausstellung einer Geburtsurkunde in Deutschland f\u00fcr Sie ganz einfach m\u00f6glich ist.<\/li>\n<li>Ein Online-Antrag ist ebenfalls eine Alternative.<\/li>\n<li>Hier erfahren Sie auch, ob noch weitere Unterlagen erforderlich sind.<\/li>\n<li>Wenn Sie die n\u00f6tigen Voraussetzungen besitzen, tr\u00e4gt man Sie in das Geburtenregister ein und Sie haben die M\u00f6glichkeit, eine Geburtsurkunde ausstellen zu lassen.<\/li>\n<li>Diese k\u00f6nnen Sie danach jederzeit neu anfordern, wenn Sie sie zum Beispiel f\u00fcr den Antrag bei der Krankenversicherung, oder aber andere Beh\u00f6rdeng\u00e4nge ben\u00f6tigen.<\/li>\n<\/ul>\n<h2>Wie lange dauert die Ausstellung einer neuen Geburtsurkunde nach Verlust?<\/h2>\n<p>Die Dauer der Neuausstellung ist vom jeweiligen Standesamt abh\u00e4ngig. Hierbei kommt es auch immer ein wenig darauf an, in welcher Form Sie diese beantragt haben. F\u00fcr gew\u00f6hnlich erfolgt die Ausstellung einer Geburtsurkunde innerhalb von <strong>drei bis f\u00fcnf Werktagen<\/strong>. Je nach Standesamt verl\u00e4ngert sich die Wartezeit m\u00f6glicherweise auf mehrere Wochen.<\/p>\n<p><strong>Tipp:<\/strong> Wenn Sie die<\/p>\n<ul>\n<li>Geburtsurkunde f\u00fcr religi\u00f6se Zwecke verloren,<\/li>\n<li>Geburtsurkunde f\u00fcr Elterngeld verloren, oder<\/li>\n<li>Geburtsurkunde f\u00fcr Kindergeld verloren<\/li>\n<\/ul>\n<p>haben, beantragen Sie sie fr\u00fch genug, um keine Wartezeiten zu riskieren.<\/p>\n<div class=\"responsive-video\"><iframe loading=lazy width=\"560\" height=\"315\" frameborder=\"0\" data-cmp-preview-mode=\"0\" data-cmp-vendor=\"s30\" data-cmp-preview-headline=\"Externer Content: Youtube Video\" data-cmp-preview-text=\"Dieser Inhalt wird von Youtube bereit gestellt. Wenn Sie diesen Inhalt aktivieren, werden ggf. personenbezogene Daten verarbeitet und Cookies gesetzt.\" src=\"about:blank\" class=\"cmplazyload responsive-content youtube-embed\" data-cmp-preview-checkbox=\"Youtube immer akzeptieren\"\n\t\tdata-cmp-src=\"\/\/www.youtube-nocookie.com\/embed\/yONnpPN1Uek?t=&rel=0\" frameborder=\"0\" \n\t\tallow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" \n\t\tallowfullscreen><\/iframe><\/div>\n<h2>Was kostet eine neue Geburtsurkunde wenn das Original verloren ist?<\/h2>\n<p>Die Geburtsurkunde verloren Kosten sind meist nicht besonders hoch und belaufen sich auf einen Betrag, der zwischen zehn und 15 Euro liegt. Wie hoch die Kosten jeweils bei Verlust der Geburtsurkunde ausfallen, ist vom jeweiligen Standesamt abh\u00e4ngig. In der Regel wird jedoch <strong>keine Extra-Geb\u00fchr<\/strong> erhoben, womit die Geburtsurkunde verloren Kosten ansteigen w\u00fcrden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Geburtsurkunde geh\u00f6rt mit zu den wichtigsten Dokumenten, die Sie f\u00fcr unterschiedliche Anl\u00e4sse ben\u00f6tigen. Dazu geh\u00f6rt zum Beispiel der Antrag auf Mitgliedschaft bei der Krankenkasse, die Anmeldung Ihrer Hochzeit auf dem Standesamt, oder aber die Er\u00f6ffnung eines neuen Bankkontos. Wie das Leben aber leider manchmal spielt, gehen Dokumente gerne verloren. Nun stellt sich die Frage, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":482,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen - Antrag24.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen - Antrag24.de\" \/>\n<meta property=\"og:description\" content=\"Die Geburtsurkunde geh\u00f6rt mit zu den wichtigsten Dokumenten, die Sie f\u00fcr unterschiedliche Anl\u00e4sse ben\u00f6tigen. Dazu geh\u00f6rt zum Beispiel der Antrag auf Mitgliedschaft bei der Krankenkasse, die Anmeldung Ihrer Hochzeit auf dem Standesamt, oder aber die Er\u00f6ffnung eines neuen Bankkontos. Wie das Leben aber leider manchmal spielt, gehen Dokumente gerne verloren. Nun stellt sich die Frage, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/\" \/>\n<meta property=\"og:site_name\" content=\"Antrag24.de\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-24T16:06:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-24T16:18:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/\"},\"author\":{\"name\":\"Maria\",\"@id\":\"https:\/\/www.antrag24.de\/c\/#\/schema\/person\/ea408ab8961736b12e0ec9aae0745ca7\"},\"headline\":\"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen\",\"datePublished\":\"2020-06-24T16:06:49+00:00\",\"dateModified\":\"2020-06-24T16:18:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/\"},\"wordCount\":956,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-scaled.jpeg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/\",\"url\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/\",\"name\":\"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen - Antrag24.de\",\"isPartOf\":{\"@id\":\"https:\/\/www.antrag24.de\/c\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-scaled.jpeg\",\"datePublished\":\"2020-06-24T16:06:49+00:00\",\"dateModified\":\"2020-06-24T16:18:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.antrag24.de\/c\/#\/schema\/person\/ea408ab8961736b12e0ec9aae0745ca7\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#primaryimage\",\"url\":\"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-scaled.jpeg\",\"contentUrl\":\"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-scaled.jpeg\",\"width\":2560,\"height\":1710,\"caption\":\"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.antrag24.de\/c\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.antrag24.de\/c\/#website\",\"url\":\"https:\/\/www.antrag24.de\/c\/\",\"name\":\"Antrag24.de\",\"description\":\"Standesamt &amp; Familienrecht - Ratgeber\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.antrag24.de\/c\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.antrag24.de\/c\/#\/schema\/person\/ea408ab8961736b12e0ec9aae0745ca7\",\"name\":\"Maria\",\"url\":\"https:\/\/www.antrag24.de\/c\/author\/maria\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen - Antrag24.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/","og_locale":"de_DE","og_type":"article","og_title":"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen - Antrag24.de","og_description":"Die Geburtsurkunde geh\u00f6rt mit zu den wichtigsten Dokumenten, die Sie f\u00fcr unterschiedliche Anl\u00e4sse ben\u00f6tigen. Dazu geh\u00f6rt zum Beispiel der Antrag auf Mitgliedschaft bei der Krankenkasse, die Anmeldung Ihrer Hochzeit auf dem Standesamt, oder aber die Er\u00f6ffnung eines neuen Bankkontos. Wie das Leben aber leider manchmal spielt, gehen Dokumente gerne verloren. Nun stellt sich die Frage, [&hellip;]","og_url":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/","og_site_name":"Antrag24.de","article_published_time":"2020-06-24T16:06:49+00:00","article_modified_time":"2020-06-24T16:18:34+00:00","og_image":[{"width":2560,"height":1710,"url":"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-scaled.jpeg","type":"image\/jpeg"}],"author":"Maria","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Maria","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#article","isPartOf":{"@id":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/"},"author":{"name":"Maria","@id":"https:\/\/www.antrag24.de\/c\/#\/schema\/person\/ea408ab8961736b12e0ec9aae0745ca7"},"headline":"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen","datePublished":"2020-06-24T16:06:49+00:00","dateModified":"2020-06-24T16:18:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/"},"wordCount":956,"commentCount":0,"image":{"@id":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#primaryimage"},"thumbnailUrl":"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-scaled.jpeg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/","url":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/","name":"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen - Antrag24.de","isPartOf":{"@id":"https:\/\/www.antrag24.de\/c\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#primaryimage"},"image":{"@id":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#primaryimage"},"thumbnailUrl":"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-scaled.jpeg","datePublished":"2020-06-24T16:06:49+00:00","dateModified":"2020-06-24T16:18:34+00:00","author":{"@id":"https:\/\/www.antrag24.de\/c\/#\/schema\/person\/ea408ab8961736b12e0ec9aae0745ca7"},"breadcrumb":{"@id":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#primaryimage","url":"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-scaled.jpeg","contentUrl":"https:\/\/www.antrag24.de\/c\/wp-content\/uploads\/2020\/06\/geburtsurkunde-verloren-standesamt1-scaled.jpeg","width":2560,"height":1710,"caption":"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.antrag24.de\/c\/geburtsurkunde-verloren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.antrag24.de\/c\/"},{"@type":"ListItem","position":2,"name":"Geburtsurkunde verloren: Wie Sie bei Verlust schnell eine neue Urkunde beantragen"}]},{"@type":"WebSite","@id":"https:\/\/www.antrag24.de\/c\/#website","url":"https:\/\/www.antrag24.de\/c\/","name":"Antrag24.de","description":"Standesamt &amp; Familienrecht - Ratgeber","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.antrag24.de\/c\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.antrag24.de\/c\/#\/schema\/person\/ea408ab8961736b12e0ec9aae0745ca7","name":"Maria","url":"https:\/\/www.antrag24.de\/c\/author\/maria\/"}]}},"_links":{"self":[{"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/posts\/460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/comments?post=460"}],"version-history":[{"count":10,"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/posts\/460\/revisions"}],"predecessor-version":[{"id":493,"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/posts\/460\/revisions\/493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/media\/482"}],"wp:attachment":[{"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/media?parent=460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/categories?post=460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.antrag24.de\/c\/wp-json\/wp\/v2\/tags?post=460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}